{"id":265,"date":"2024-04-24T14:32:13","date_gmt":"2024-04-24T04:32:13","guid":{"rendered":"https:\/\/figarigroup.com\/en-ca\/?page_id=265"},"modified":"2024-10-21T12:14:36","modified_gmt":"2024-10-21T01:14:36","slug":"office-design","status":"publish","type":"page","link":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/","title":{"rendered":"Office Design"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":263,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-265","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Office Design - Figari Group Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Office Design - Figari Group Canada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Figari Group Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T01:14:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/office-design\\\/\",\"url\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/office-design\\\/\",\"name\":\"Office Design - Figari Group Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/#website\"},\"datePublished\":\"2024-04-24T04:32:13+00:00\",\"dateModified\":\"2024-10-21T01:14:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/office-design\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/office-design\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/office-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Build\",\"item\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/build\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Office Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/#website\",\"url\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/\",\"name\":\"Figari Group Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/figarigroup.com\\\/en-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Office Design - Figari Group Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/","og_locale":"en_US","og_type":"article","og_title":"Office Design - Figari Group Canada","og_url":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/","og_site_name":"Figari Group Canada","article_modified_time":"2024-10-21T01:14:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/","url":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/","name":"Office Design - Figari Group Canada","isPartOf":{"@id":"https:\/\/figarigroup.com\/en-ca\/#website"},"datePublished":"2024-04-24T04:32:13+00:00","dateModified":"2024-10-21T01:14:36+00:00","breadcrumb":{"@id":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/figarigroup.com\/en-ca\/build\/office-design\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/figarigroup.com\/en-ca\/build\/office-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/figarigroup.com\/en-ca\/"},{"@type":"ListItem","position":2,"name":"Build","item":"https:\/\/figarigroup.com\/en-ca\/build\/"},{"@type":"ListItem","position":3,"name":"Office Design"}]},{"@type":"WebSite","@id":"https:\/\/figarigroup.com\/en-ca\/#website","url":"https:\/\/figarigroup.com\/en-ca\/","name":"Figari Group Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/figarigroup.com\/en-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/pages\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/comments?post=265"}],"version-history":[{"count":0,"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/pages\/265\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/pages\/263"}],"wp:attachment":[{"href":"https:\/\/figarigroup.com\/en-ca\/wp-json\/wp\/v2\/media?parent=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}